{"id":637,"date":"2018-03-19T16:15:37","date_gmt":"2018-03-19T15:15:37","guid":{"rendered":"http:\/\/www.palabressansfrontieres.fr\/?p=637"},"modified":"2018-03-19T16:27:46","modified_gmt":"2018-03-19T15:27:46","slug":"newsletter-n4-2018","status":"publish","type":"post","link":"https:\/\/www.palabressansfrontieres.fr\/web\/newsletter-n4-2018\/","title":{"rendered":"Newsletter n\u00b04 &#8211; 2018"},"content":{"rendered":"<p><strong>Newsletter n\u00b04 &#8211;\u00a0 f\u00e9vrier 2018<\/strong><\/p>\n<p style=\"text-align: center;\"><strong> Chers amis palabreurs,<br \/>\n<\/strong><\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s quelques mois d\u2019acclimatation dans notre nouvel univers des Cara\u00efbes, quelques nouvelles de Palabres sans Fronti\u00e8res Martinique. D\u2019abord nos remerciements pour nos nouveaux adh\u00e9rents qui se mobilisent \u00e0 chaque \u00e9v\u00e8nement de l\u2019association, sans eux notre adaptation aurait \u00e9t\u00e9 plus longue.<\/p>\n<p style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.palabressansfrontieres.fr\/newsletter-n4-2018\/samba-1\/\" rel=\"attachment wp-att-638\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-638 size-full\" src=\"http:\/\/www.palabressansfrontieres.fr\/wp-content\/uploads\/2018\/03\/samba-1.jpg\" alt=\"\" width=\"246\" height=\"180\" \/><\/a><\/strong><strong>En octobre<\/strong> les \u00e9v\u00e9nements ont d\u00e9marr\u00e9 avec la manifestation contre l\u2019esclavage en Libye organis\u00e9e \u00e0 Fort de France par le r\u00e9seau panafricain.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: left;\"><strong><br \/>\n<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: left;\"><strong><br \/>\n<a href=\"http:\/\/www.palabressansfrontieres.fr\/newsletter-n4-2018\/reu\/\" rel=\"attachment wp-att-640\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-640 alignright\" src=\"http:\/\/www.palabressansfrontieres.fr\/wp-content\/uploads\/2018\/03\/reu-e1521473091594.jpg\" alt=\"\" width=\"246\" height=\"170\" \/><\/a><a href=\"http:\/\/www.palabressansfrontieres.fr\/newsletter-n4-2018\/samba-2\/\" rel=\"attachment wp-att-639\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-639 alignright\" src=\"http:\/\/www.palabressansfrontieres.fr\/wp-content\/uploads\/2018\/03\/samba-2-e1521473121151.jpg\" alt=\"\" width=\"146\" height=\"170\" \/><\/a>Le 30 novembre 2017<br \/>\n<\/strong>nous avons particip\u00e9 au Festival Alimentaire sur l\u2019agriculture biologique en Afrique au centre culturel du Lamentin.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.palabressansfrontieres.fr\/newsletter-n4-2018\/suite\/\" rel=\"attachment wp-att-641\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-641 size-medium\" src=\"http:\/\/www.palabressansfrontieres.fr\/wp-content\/uploads\/2018\/03\/suite-300x162.jpg\" alt=\"\" width=\"300\" height=\"162\" srcset=\"https:\/\/www.palabressansfrontieres.fr\/wp-content\/uploads\/2018\/03\/suite-300x162.jpg 300w, https:\/\/www.palabressansfrontieres.fr\/wp-content\/uploads\/2018\/03\/suite.jpg 349w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Le 27 d\u00e9cembre 2017<\/strong>: Une vente de g\u00e2teaux africains et boissons au centre commercial La Gal\u00e9ria pour soutenir nos partenaires du S\u00e9n\u00e9gal. Recettes\u00a0: 340\u20ac\u00a0 Merci \u00e0 nos nouveaux adh\u00e9rents qui se mobilisent \u00e0 chaque \u00e9v\u00e8nement de l\u2019association<\/p>\n<p><strong><a href=\"http:\/\/www.palabressansfrontieres.fr\/newsletter-n4-2018\/fraternite\/\" rel=\"attachment wp-att-642\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-642 alignleft\" src=\"http:\/\/www.palabressansfrontieres.fr\/wp-content\/uploads\/2018\/03\/fraternite-300x242.jpg\" alt=\"\" width=\"300\" height=\"242\" srcset=\"https:\/\/www.palabressansfrontieres.fr\/wp-content\/uploads\/2018\/03\/fraternite-300x242.jpg 300w, https:\/\/www.palabressansfrontieres.fr\/wp-content\/uploads\/2018\/03\/fraternite.jpg 335w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/strong><strong>Le 28 janvier 2018<\/strong>\u00a0: Journ\u00e9e de la Fraternit\u00e9 avec le S\u00e9n\u00e9gal organis\u00e9e par le club de service Kiwanis de Fort de France, l\u2019association des amis du S\u00e9n\u00e9gal et Palabres sans Fronti\u00e8res \u00e0 l\u2019hotel\u00a0 Squash de Fort de France.<\/p>\n<p><strong>Au programme\u00a0:<br \/>\n<\/strong>Conf\u00e9rence sur les opportunit\u00e9s\u00a0 d\u2019investissement au \u00a0S\u00e9n\u00e9gal par Ibrahima Dia professeur \u00e0 l\u2019universit\u00e9 de Fort de France Diaporama sur le tourisme solidaire: notre exp\u00e9rience au S\u00e9n\u00e9gal par Samba Gaye; Repas s\u00e9n\u00e9galais; D\u00e9fil\u00e9 de mode s\u00e9n\u00e9galaise;<br \/>\n<strong>Concentration et\u00a0\u00a0 Bonne humeur\u00a0!<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Janvier 2018<\/strong>\u00a0: Une nouvelle offre de s\u00e9jour\u00a0: Un circuit de 10 jours Keur Samba Yacine NDem\u00a0 Lompoul Saint Louis modulable selon les besoins \u00e0 2 \u00e0 3 lieux. Nous travaillons sur une nouvelle offre de tourisme alternatif en Martinique pour faire d\u00e9couvrir l\u2019autre facette moins connue\u00a0: agriculture bio, la culture musicale de racines africaines, la cuisine locale.\u00a0 Nous vous informerons prochainement\u2026<\/p>\n<p style=\"text-align: justify;\"><strong>Apr\u00e8s 1 an et demi de pr\u00e9sence en Martinique, Palabres commence \u00e0 poser ses marques. Petit \u00e0 petit l\u2019oiseau fait son nid. Dans le grand oc\u00e9an des tours op\u00e9rateurs et des paquebots de croisi\u00e8res, notre petite structure essaie de trouver sa place pour diffuser un message de solidarit\u00e9, justice et respect de l\u2019humain et de l\u2019environnement.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Newsletter n\u00b04 &#8211;\u00a0 f\u00e9vrier 2018 Chers amis palabreurs, Apr\u00e8s quelques mois d\u2019acclimatation dans notre nouvel univers des Cara\u00efbes, quelques nouvelles de Palabres sans Fronti\u00e8res Martinique. D\u2019abord nos remerciements pour nos nouveaux adh\u00e9rents qui se mobilisent \u00e0 chaque \u00e9v\u00e8nement de l\u2019association,&hellip; <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-637","post","type-post","status-publish","format-standard","hentry","category-actualites"],"_links":{"self":[{"href":"https:\/\/www.palabressansfrontieres.fr\/web\/wp-json\/wp\/v2\/posts\/637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.palabressansfrontieres.fr\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.palabressansfrontieres.fr\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.palabressansfrontieres.fr\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.palabressansfrontieres.fr\/web\/wp-json\/wp\/v2\/comments?post=637"}],"version-history":[{"count":12,"href":"https:\/\/www.palabressansfrontieres.fr\/web\/wp-json\/wp\/v2\/posts\/637\/revisions"}],"predecessor-version":[{"id":654,"href":"https:\/\/www.palabressansfrontieres.fr\/web\/wp-json\/wp\/v2\/posts\/637\/revisions\/654"}],"wp:attachment":[{"href":"https:\/\/www.palabressansfrontieres.fr\/web\/wp-json\/wp\/v2\/media?parent=637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.palabressansfrontieres.fr\/web\/wp-json\/wp\/v2\/categories?post=637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.palabressansfrontieres.fr\/web\/wp-json\/wp\/v2\/tags?post=637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}