{"id":4,"count":3,"description":"L'association Palabres sans Fronti\u00e8res est une association loi 1901  - agr\u00e9\u00e9e Jeunesse et Sports et Education Populaire. Elle a pour but de favoriser une citoyennet\u00e9 des jeunes ouverte sur le Monde. Elle met en \u0153uvre des solidarit\u00e9s culturelles et interculturelles, \u00e0 travers des animations, des formations des \u00e9changes et la promotion du tourisme solidaire par des voyages .","link":"https:\/\/www.palabressansfrontieres.fr\/web\/category\/qui-sommes-nous\/","name":"Qui sommes nous ?","slug":"qui-sommes-nous","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.palabressansfrontieres.fr\/web\/wp-json\/wp\/v2\/categories\/4","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.palabressansfrontieres.fr\/web\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.palabressansfrontieres.fr\/web\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.palabressansfrontieres.fr\/web\/wp-json\/wp\/v2\/posts?categories=4"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}